{"id":30110,"date":"2026-04-08T13:19:27","date_gmt":"2026-04-08T12:19:27","guid":{"rendered":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/"},"modified":"2026-09-02T19:15:13","modified_gmt":"2026-09-02T18:15:13","slug":"kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm","status":"publish","type":"product","link":"https:\/\/lamillou.ch\/en\/product\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/","title":{"rendered":"Kopfkissen Baumwolle LITTLE SAVANNAH &#8211; XL &#8211; 50 x 70 cm"},"content":{"rendered":"<p>Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine antiallergische F\u00fcllung, die gleichzeitig elastisch und weich ist. Zusammen mit der Decke bildet es das perfekte Set f\u00fcr Ihr Baby f\u00fcr das Kinderzimmer!<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus<\/p>","protected":false},"featured_media":31314,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[88],"product_cat":[267],"product_tag":[],"class_list":["post-30110","product","type-product","status-publish","has-post-thumbnail","product_brand-la-millou","product_cat-bettkissen","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm - lamillou.ch<\/title>\n<meta name=\"description\" content=\"Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamillou.ch\/en\/product\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm - lamillou.ch\" \/>\n<meta property=\"og:description\" content=\"Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamillou.ch\/en\/product\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"lamillou.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T18:15:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lamillou.ch\/wp-content\/uploads\/2026\/04\/image_1920_OPc4I.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/\",\"url\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/\",\"name\":\"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm - lamillou.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamillou.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamillou.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/image_1920_OPc4I.jpeg\",\"datePublished\":\"2026-04-08T12:19:27+00:00\",\"dateModified\":\"2026-09-02T18:15:13+00:00\",\"description\":\"Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lamillou.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/image_1920_OPc4I.jpeg\",\"contentUrl\":\"https:\\\/\\\/lamillou.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/image_1920_OPc4I.jpeg\",\"width\":1920,\"height\":1920,\"caption\":\"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm Hauptbild\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamillou.ch\\\/produkt\\\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lamillou.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lamillou.ch\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kopfkissen Baumwolle LITTLE SAVANNAH &#8211; XL &#8211; 50 x 70 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamillou.ch\\\/#website\",\"url\":\"https:\\\/\\\/lamillou.ch\\\/\",\"name\":\"lamillou.ch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamillou.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm - lamillou.ch","description":"Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamillou.ch\/en\/product\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/","og_locale":"en_GB","og_type":"article","og_title":"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm - lamillou.ch","og_description":"Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine","og_url":"https:\/\/lamillou.ch\/en\/product\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/","og_site_name":"lamillou.ch","article_modified_time":"2026-09-02T18:15:13+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/lamillou.ch\/wp-content\/uploads\/2026\/04\/image_1920_OPc4I.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/","url":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/","name":"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm - lamillou.ch","isPartOf":{"@id":"https:\/\/lamillou.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/#primaryimage"},"image":{"@id":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/#primaryimage"},"thumbnailUrl":"https:\/\/lamillou.ch\/wp-content\/uploads\/2026\/04\/image_1920_OPc4I.jpeg","datePublished":"2026-04-08T12:19:27+00:00","dateModified":"2026-09-02T18:15:13+00:00","description":"Ein klassisches Kinderkissen mit einer d\u00fcnnen F\u00fcllung f\u00fcr einen bequemen Schlaf bei Tag und Nacht. Das Kissen ist beidseitig aus Baumwolle und hat eine","breadcrumb":{"@id":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/#primaryimage","url":"https:\/\/lamillou.ch\/wp-content\/uploads\/2026\/04\/image_1920_OPc4I.jpeg","contentUrl":"https:\/\/lamillou.ch\/wp-content\/uploads\/2026\/04\/image_1920_OPc4I.jpeg","width":1920,"height":1920,"caption":"Kopfkissen Baumwolle LITTLE SAVANNAH - XL - 50 x 70 cm Hauptbild"},{"@type":"BreadcrumbList","@id":"https:\/\/lamillou.ch\/produkt\/kopfkissen-baumwolle-little-savannah-xl-50-x-70-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lamillou.ch\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lamillou.ch\/shop\/"},{"@type":"ListItem","position":3,"name":"Kopfkissen Baumwolle LITTLE SAVANNAH &#8211; XL &#8211; 50 x 70 cm"}]},{"@type":"WebSite","@id":"https:\/\/lamillou.ch\/#website","url":"https:\/\/lamillou.ch\/","name":"lamillou.ch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamillou.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/product\/30110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/comments?post=30110"}],"version-history":[{"count":0,"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/product\/30110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/media\/31314"}],"wp:attachment":[{"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/media?parent=30110"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/product_brand?post=30110"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/product_cat?post=30110"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamillou.ch\/en\/wp-json\/wp\/v2\/product_tag?post=30110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}